{"id":12445,"count":3,"description":"","link":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/tag\/ransomware\/","name":"Ransomware","slug":"ransomware","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.13 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ransomware Archives - Cybersecurity Exchange<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ransomware Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/tag\/ransomware\/\" \/>\n<meta property=\"og:site_name\" content=\"Cybersecurity Exchange\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/tag\\\/ransomware\\\/\",\"url\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/tag\\\/ransomware\\\/\",\"name\":\"Ransomware Archives - Cybersecurity Exchange\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/tag\\\/ransomware\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/tag\\\/ransomware\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eccouncil.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cybersecurity Exchange\",\"item\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ransomware\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/#website\",\"url\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/\",\"name\":\"Cybersecurity Exchange\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/#organization\",\"name\":\"Cybersecurity Exchange\",\"url\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Cybersecurity Exchange\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eccouncil.org\\\/cybersecurity-exchange\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ransomware Archives - Cybersecurity Exchange","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Ransomware Archives","og_url":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/tag\/ransomware\/","og_site_name":"Cybersecurity Exchange","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/tag\/ransomware\/","url":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/tag\/ransomware\/","name":"Ransomware Archives - Cybersecurity Exchange","isPartOf":{"@id":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/#website"},"breadcrumb":{"@id":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/tag\/ransomware\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/tag\/ransomware\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eccouncil.org\/"},{"@type":"ListItem","position":2,"name":"Cybersecurity Exchange","item":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/"},{"@type":"ListItem","position":3,"name":"Ransomware"}]},{"@type":"WebSite","@id":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/#website","url":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/","name":"Cybersecurity Exchange","description":"","publisher":{"@id":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/#organization","name":"Cybersecurity Exchange","url":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Cybersecurity Exchange"},"image":{"@id":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/wp-json\/wp\/v2\/tags\/12445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.eccouncil.org\/cybersecurity-exchange\/wp-json\/wp\/v2\/posts?tags=12445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}